{"id":90,"date":"2018-03-27T12:55:40","date_gmt":"2018-03-27T12:55:40","guid":{"rendered":"http:\/\/111.118.182.80\/~bookstore\/cag-it-audit\/?page_id=90"},"modified":"2020-12-02T16:08:48","modified_gmt":"2020-12-02T10:38:48","slug":"login","status":"publish","type":"page","link":"https:\/\/wgei.intosaicommunity.net\/es\/login\/","title":{"rendered":"Login"},"content":{"rendered":"<div class=\"container-fluid innerpage loginbx\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-sm-12\">\n\r\n\r\n<div id=\"wpum-form-wpum_loginform\" class=\"wpum-login-form\" data-redirect=\"https:\/\/wgei.intosaicommunity.net\/es\/profile\/\">\r\n\r\n\t\r\n\t<form name=\"wpum_loginform\" id=\"wpum_loginform\" action=\"https:\/\/wgei.intosaicommunity.net\/wp-login.php\" method=\"post\"><p class=\"login-username\">\n\t\t\t\t<label for=\"wpum_loginformuser_login\">Username or email<\/label>\n\t\t\t\t<input type=\"text\" name=\"log\" id=\"wpum_loginformuser_login\" autocomplete=\"username\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p><p class=\"login-password\">\n\t\t\t\t<label for=\"wpum_loginformuser_pass\">Password<\/label>\n\t\t\t\t<input type=\"password\" name=\"pwd\" id=\"wpum_loginformuser_pass\" autocomplete=\"current-password\" spellcheck=\"false\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p><input type=\"hidden\" name=\"wpum_is_login_form\" value=\"wpum\"><input type=\"hidden\" name=\"wpum_test\" value=\"\"><p class=\"login-remember\"><label><input name=\"rememberme\" type=\"checkbox\" id=\"wpum_loginformrememberme\" value=\"forever\" \/> Remember Me<\/label><\/p><p class=\"login-submit\">\n\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wpum_loginformwp-submit\" class=\"button button-primary\" value=\"Login\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"https:\/\/wgei.intosaicommunity.net\/es\/profile\/\" \/>\n\t\t\t<\/p><\/form>\r\n\t\r\n<\/div>\r\n\r\n<div class=\"wpum-helper-links\">\r\n\r\n\t\r\n\t\t<p class=\"wpum-register-url\">\r\n\t\tDon't have an account? <a href=\"https:\/\/wgei.intosaicommunity.net\/es\/register\/\">Signup Now &raquo;<\/a>\t<\/p>\r\n\t\r\n\t\t<p class=\"wpum-password-recovery-url\">\r\n\t\t<a href=\"https:\/\/wgei.intosaicommunity.net\/es\/password-reset\/\">\r\n\t\t\tLost your password?\t\t<\/a>\r\n\t<\/p>\r\n\t\r\n<\/div>\r\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":42,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/pages\/90"}],"collection":[{"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":8,"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":5285,"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/pages\/90\/revisions\/5285"}],"wp:attachment":[{"href":"https:\/\/wgei.intosaicommunity.net\/es\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}