{"id":33,"count":1,"description":"","link":"https:\/\/wgei.intosaicommunity.net\/de\/category\/wgei-members-meetings\/","name":"WGEI Members Meetings","slug":"wgei-members-meetings","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/wgei.intosaicommunity.net\/de\/wp-json\/wp\/v2\/categories\/33"}],"collection":[{"href":"https:\/\/wgei.intosaicommunity.net\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/wgei.intosaicommunity.net\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/wgei.intosaicommunity.net\/de\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}